<ul id="share-buttons"><li class="facebook"><div class="fb-like" data-href="https://www.pqn.com.br/portal/johnny-herno-apresenta-o-berimlata/" data-send="false" data-layout="button_count" data-width="66" data-show-faces="false"></div></li><li class="twitter"><a href="http://twitter.com/share" class="twitter-share-button" data-url="https://www.pqn.com.br/portal/johnny-herno-apresenta-o-berimlata/" data-count="none">Tweet</a></li><li class="google"><div class="g-plusone" data-size="medium" data-href="https://www.pqn.com.br/portal/johnny-herno-apresenta-o-berimlata/"></div></li><li class="linkedin"><script type="IN/Share" data-url="https://www.pqn.com.br/portal/johnny-herno-apresenta-o-berimlata/" data-counter="right"></script></li></ul>{"id":12089,"date":"2024-04-11T17:00:03","date_gmt":"2024-04-11T20:00:03","guid":{"rendered":"https:\/\/www.pqn.com.br\/portal\/?p=12089"},"modified":"2024-04-11T17:00:03","modified_gmt":"2024-04-11T20:00:03","slug":"johnny-herno-apresenta-o-berimlata","status":"publish","type":"post","link":"https:\/\/www.pqn.com.br\/portal\/johnny-herno-apresenta-o-berimlata\/","title":{"rendered":"Johnny Herno apresenta o &#8220;berimlata&#8221;"},"content":{"rendered":"<div id=\"attachment_12090\" style=\"width: 610px\" class=\"wp-caption alignleft\"><img aria-describedby=\"caption-attachment-12090\" loading=\"lazy\" class=\"size-full wp-image-12090\" src=\"https:\/\/www.pqn.com.br\/portal\/wp-content\/uploads\/2024\/04\/Johnny-Herno-1-Foto-Pablo-Bernardo.jpg\" alt=\"\" width=\"600\" height=\"270\" srcset=\"https:\/\/www.pqn.com.br\/portal\/wp-content\/uploads\/2024\/04\/Johnny-Herno-1-Foto-Pablo-Bernardo.jpg 600w, https:\/\/www.pqn.com.br\/portal\/wp-content\/uploads\/2024\/04\/Johnny-Herno-1-Foto-Pablo-Bernardo-300x135.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><p id=\"caption-attachment-12090\" class=\"wp-caption-text\">Foto: Pablo Bernardo<\/p><\/div>\n<p>No Jap\u00e3o, tsuru \u00e9 uma ave sagrada que simboliza boa sorte, felicidade, longevidade e fortuna. \u00c9, tamb\u00e9m, considerado o p\u00e1ssaro companheiro dos eremitas, que se refugiavam nas montanhas para meditar, pois podia viver at\u00e9 mil anos, reza a lenda. Percussionista, compositor e inventor de instrumentos, Johnny Herno pegou emprestado o nome desse animal fabular para dar t\u00edtulo a seu primeiro \u00e1lbum solo. Rico em significados, tal como o tsuru oriental, o \u201cTsuru\u201d do artista mineiro celebra a pot\u00eancia da produ\u00e7\u00e3o percussiva contempor\u00e2nea e da inventividade musical brasileira, al\u00e9m de prestar homenagem ao m\u00fasico pernambucano Nan\u00e1 Vasconcelos (1944-2016) e aos povos da floresta. O \u00e1lbum apresenta 11 faixas autorais in\u00e9ditas, sendo uma com \u201cparticipa\u00e7\u00e3o\u201d do ilustre homenageado.<\/p>\n<p>Criador do fascinante &#8220;berimlata&#8221; \u2013 tipo de monoc\u00f3rdio feito com arco de semente de biriba, tal qual o berimbau, mas com um arame de pneu e um lat\u00e3o de tinta no lugar da caba\u00e7a \u2013, Johnny Herno lan\u00e7a o disco entre abril e julho deste ano, com uma s\u00e9rie de quatro shows com convidados, al\u00e9m de oficinas e exposi\u00e7\u00e3o, em Belo Horizonte. A estreia \u00e9 no dia 20 de abril, s\u00e1bado, mesma data em que o \u00e1lbum chega \u00e0s plataformas digitais de streaming. O show acontece \u00e0s 19h, no Teatro Raul Bel\u00e9m Machado, com participa\u00e7\u00f5es do percussionista Daniel Guedes e do guitarrista e produtor musical Andr\u00e9 Cabelo. Os ingressos s\u00e3o gratuitos, est\u00e3o dispon\u00edveis para retirada online pela Sympla neste link e tamb\u00e9m ser\u00e3o distribu\u00eddos na portaria, a partir de uma hora antes da apresenta\u00e7\u00e3o.<\/p>\n<p>Ap\u00f3s a estreia, a circula\u00e7\u00e3o de \u201cTsuru\u201d contar\u00e1 com outras tr\u00eas datas: dia 1\u00ba de junho, s\u00e1bado, \u00e0s 15h, no Parque Lagoa do Nado, com os percussionistas Carlinhos Ferreira e Babilak Bah; dia 2 de junho, domingo, \u00e0s 10h, no Parque Ecol\u00f3gico e Cultural Professor Marcos Mazzoni, com o pianista Rafael Martini; e dia 7 de julho, domingo, \u00e0s 15h, no Centro Cultural Vila F\u00e1tima, com a cantora Elisa de Sena. Paralelamente aos shows, o artista ministra a oficina \u201cO processo criativo que norteia o compositor intuitivo\u201d no dia 2 de maio, quinta-feira, \u00e0s 10h, no Centro Cultural Venda Nova; e no dia 4 de junho, ter\u00e7a-feira, \u00e0s 14h, no Centro Cultural S\u00e3o Geraldo. Para completar o lan\u00e7amento, ser\u00e1 realizada uma exposi\u00e7\u00e3o, em junho, em data a confirmar, no Centro Cultural S\u00e3o Bernardo, que apresenta o &#8220;berimlata&#8221; e conta mais a hist\u00f3ria do instrumento.<\/p>\n<p>\u201cNesta primeira apresenta\u00e7\u00e3o, teremos as participa\u00e7\u00f5es de dois m\u00fasicos que gravaram o \u00e1lbum: Daniel Guedes, nas percuss\u00f5es; e Andr\u00e9 Cabelo, nas cordas e no som\u201d, sublinha Johnny Herno, destacando que \u201cTsuru\u201d foi gravado no est\u00fadio Engenho, \u201cpilotado\u201d por Cabelo, prestigiado produtor musical de BH e guitarrista da ic\u00f4nica banda de metal Chakal. \u201cAl\u00e9m de ter gravado o disco, Cabelo participou com sua guitarra, que envolveu o tribal e a distor\u00e7\u00e3o numa refer\u00eancia ao estilo de som pesado. Um encontro da percuss\u00e3o com a frequ\u00eancia do metal, na m\u00fasica \u2018Carne Seca de Cigarra\u2019, que tamb\u00e9m traz o baque dos tambores de Daniel Guedes. Bebendo da fonte do tambor mineiro, o percussionista assina, ainda, os arranjos de cu\u00edca e pandeiro em \u2018O Sol Afinou Zabumba\u2019\u201d, completa.<\/p>\n<p><strong>Sons e homenagens<br \/>\n<\/strong>O show &#8220;Tsuru&#8221; \u00e9 um solo de percuss\u00e3o e canto \u00e0 capela, em linguagem eletroac\u00fastica, com ditos populares e aboios, evocando os povos da floresta e homenageando o percussionista pernambucano Nan\u00e1 Vasconcelos. \u201cQuem me apresentou a arte de Nan\u00e1 foi o m\u00fasico paraibano Babilack Bah, com quem tenho uma parceria musical de mais de 24 anos. Em uma audi\u00e7\u00e3o do disco \u2018Cantando Est\u00f3rias\u2019 (1994), foi imediata a maneira de Nan\u00e1 apresentar a percuss\u00e3o como uma orquestra popular de diferentes timbres, bem como sua vontade de propagar a Amaz\u00f4nia como reservat\u00f3rio de vida e sabedoria\u201d, conta Johnny, recordando-se das trocas que teve com o m\u00fasico pernambucano. \u201cTivemos uma conversa depois de uma oficina que fiz com ele em S\u00e3o. Lembro-me que ele me estendeu a m\u00e3o e disse: \u2018Johnny, eu fa\u00e7o isso para que os outros tamb\u00e9m possam fazer\u2019. Essa frase foi como um sol a iluminar meu caminho, foi como uma ben\u00e7\u00e3o\u201d.<\/p>\n<p>Durante o per\u00edodo pand\u00eamico, quando o disco \u201cTsuru\u201d foi maturado, Johnny pegou-se tocado por um depoimento de Nan\u00e1. \u201cEle recitava, depois de uma sess\u00e3o de quimioterapia, uma mensagem vinda em sonho, que dizia a ele estar cheio de vida, de m\u00fasica, de uma vibra\u00e7\u00e3o de v\u00e1rias ramifica\u00e7\u00f5es religiosas. Fiquei energizado pela fala do mestre\u201d, relembra. \u201cEnt\u00e3o, liguei para Patr\u00edcia Vasconcelos, vi\u00fava e curadora da obra de Nan\u00e1, e pedi autoriza\u00e7\u00e3o para usar, na introdu\u00e7\u00e3o de \u2018O Berimlata\u2019, a risada do mestre, uma de suas marcas registradas. Ela n\u00e3o s\u00f3 deu a ben\u00e7\u00e3o, como disse que eu tinha sentido a fundo a alma de Nan\u00e1. Na m\u00fasica, usamos tamb\u00e9m o poema \u2018Um budista afro-budista\u2019, recitado por ele, e um poema meu, chamado \u2018Tsuru Nan\u00e1\u2019. Infelizmente, Nan\u00e1 faleceu antes que eu pudesse apresent\u00e1-lo ao &#8216;berimlata&#8217;, instrumento que deriva do berimbau da capoeira, que ele tanto propagou pelo mundo\u201d, completa o m\u00fasico, que tamb\u00e9m utiliza no disco objetos como penicos e brinquedos, al\u00e9m de sons onomatopaicos, gritos, sussurros e poesias.<\/p>\n<p>Defensor do meio ambiente, dos povos da floresta e dos rios e nascentes, Johnny Herno presta outras homenagens em seu primeiro disco solo. \u201cAl\u00e9m de homenagear Nan\u00e1 Vasconcelos, \u2018Tsuru\u2019 traz uma responsabilidade ambiental muito grande em defesa das nascentes e rios, tratando temas como a cigarra, inseto cujo dito popular o canto tem o poder m\u00e1gico de evocar as \u00e1guas, em \u2018Carne Seca de Cigarra\u2019; e o mitol\u00f3gico, no encontro do minotauro e da mula sem cabe\u00e7a, da f\u00eanix e do sagit\u00e1rio, em \u2018A Encruzilhada dos Cardumes Carn\u00edvoros\u2019. Outra homenagem \u00e9 dedicada ao artista do ru\u00eddo Babilack Bah, que traz a enxada \u00e9 apresentada como ferramenta-arma e instrumento musical na can\u00e7\u00e3o \u2018A Cura da Fome\u2019. E h\u00e1, ainda, a participa\u00e7\u00e3o mais que especial de meus pais, Eunice e Hor\u00e1cio, na faixa \u2018Ben\u00e7a M\u00e3e Ben\u00e7a Pai\u2019, que retrata o percurso rumo ao \u00f3vulo\u201d, afirma Johnny, ressaltando que a arte de \u201cTsuru\u201d \u00e9 assinada pelo artista visual Caio Ronin, que tamb\u00e9m \u00e9 natural de Santa Luzia.<\/p>\n<p>Depois da circula\u00e7\u00e3o, Johnny Herno pretende juntar no palco, em sua cidade-natal, parceiros com quem se apresenta desde o come\u00e7o de sua trajet\u00f3ria. \u201cQuero fazer uma grande apresenta\u00e7\u00e3o reunindo artistas que acompanho desde o in\u00edcio da carreira, como Tom nascimento, Seu Ribeiro, Erick Duarte e Gui ventura. E a\u00ed o voo \u2018 Tsuru\u2019 parte pelo Brasil e, quem sabe, pelo mundo, para nutrir o planeta com o bem estar da cria\u00e7\u00e3o; apresentando a percuss\u00e3o como elemento fundamental da composi\u00e7\u00e3o, a exemplo de grandes m\u00fasicos como Nan\u00e1 Vasconcelos, Airto Morera, Djalma Corr\u00eaa, Hermeto Paschoal, Babilack Bah e Carlinhos Ferreira, todos banhados pela cultura popular e a m\u00fasica s\u00fabita\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p> [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":12090,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[155],"tags":[14656,14659,48,14655,14658,14657],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Johnny Herno apresenta o &quot;berimlata&quot;<\/title>\n<meta name=\"description\" content=\"PQN - O portal da Comunica\u00e7\u00e3o!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pqn.com.br\/portal\/johnny-herno-apresenta-o-berimlata\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Johnny Herno apresenta o &quot;berimlata&quot;\" \/>\n<meta property=\"og:description\" content=\"PQN - O portal da Comunica\u00e7\u00e3o!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pqn.com.br\/portal\/johnny-herno-apresenta-o-berimlata\/\" \/>\n<meta property=\"og:site_name\" content=\"PQN - O portal da Comunica\u00e7\u00e3o!\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-11T20:00:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pqn.com.br\/portal\/wp-content\/uploads\/2024\/04\/Johnny-Herno-1-Foto-Pablo-Bernardo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"270\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/www.pqn.com.br\/portal\/#\/schema\/person\/641f45d95f0e5edb9d04765e83d61524\",\"name\":\"Americo Alexandre Cianfarani Xavier\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.pqn.com.br\/portal\/#personlogo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a90e5be7c65885cf85322a30c9d98842?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a90e5be7c65885cf85322a30c9d98842?s=96&d=mm&r=g\",\"caption\":\"Americo Alexandre Cianfarani Xavier\"},\"logo\":{\"@id\":\"https:\/\/www.pqn.com.br\/portal\/#personlogo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pqn.com.br\/portal\/#website\",\"url\":\"https:\/\/www.pqn.com.br\/portal\/\",\"name\":\"PQN - O portal da Comunica\u00e7\u00e3o!\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.pqn.com.br\/portal\/#\/schema\/person\/641f45d95f0e5edb9d04765e83d61524\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pqn.com.br\/portal\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.pqn.com.br\/portal\/johnny-herno-apresenta-o-berimlata\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/www.pqn.com.br\/portal\/wp-content\/uploads\/2024\/04\/Johnny-Herno-1-Foto-Pablo-Bernardo.jpg\",\"contentUrl\":\"https:\/\/www.pqn.com.br\/portal\/wp-content\/uploads\/2024\/04\/Johnny-Herno-1-Foto-Pablo-Bernardo.jpg\",\"width\":600,\"height\":270,\"caption\":\"Foto: Pablo Bernardo\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pqn.com.br\/portal\/johnny-herno-apresenta-o-berimlata\/#webpage\",\"url\":\"https:\/\/www.pqn.com.br\/portal\/johnny-herno-apresenta-o-berimlata\/\",\"name\":\"Johnny Herno apresenta o \\\"berimlata\\\"\",\"isPartOf\":{\"@id\":\"https:\/\/www.pqn.com.br\/portal\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.pqn.com.br\/portal\/johnny-herno-apresenta-o-berimlata\/#primaryimage\"},\"datePublished\":\"2024-04-11T20:00:03+00:00\",\"dateModified\":\"2024-04-11T20:00:03+00:00\",\"description\":\"PQN - O portal da Comunica\u00e7\u00e3o!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.pqn.com.br\/portal\/johnny-herno-apresenta-o-berimlata\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.pqn.com.br\/portal\/johnny-herno-apresenta-o-berimlata\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.pqn.com.br\/portal\/johnny-herno-apresenta-o-berimlata\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.pqn.com.br\/portal\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Johnny Herno apresenta o &#8220;berimlata&#8221;\"}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/www.pqn.com.br\/portal\/johnny-herno-apresenta-o-berimlata\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.pqn.com.br\/portal\/johnny-herno-apresenta-o-berimlata\/#webpage\"},\"author\":{\"@id\":\"https:\/\/www.pqn.com.br\/portal\/#\/schema\/person\/bd54e0682ae91879b6f7dc07b961c245\"},\"headline\":\"Johnny Herno apresenta o &#8220;berimlata&#8221;\",\"datePublished\":\"2024-04-11T20:00:03+00:00\",\"dateModified\":\"2024-04-11T20:00:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.pqn.com.br\/portal\/johnny-herno-apresenta-o-berimlata\/#webpage\"},\"wordCount\":1220,\"publisher\":{\"@id\":\"https:\/\/www.pqn.com.br\/portal\/#\/schema\/person\/641f45d95f0e5edb9d04765e83d61524\"},\"image\":{\"@id\":\"https:\/\/www.pqn.com.br\/portal\/johnny-herno-apresenta-o-berimlata\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.pqn.com.br\/portal\/wp-content\/uploads\/2024\/04\/Johnny-Herno-1-Foto-Pablo-Bernardo.jpg\",\"keywords\":[\"\\\"berimlata\\\"\",\"Babilack Bah\",\"capa\",\"Johnny Herno\",\"Parque Ecol\u00f3gico e Cultural Professor Marcos Mazzoni\",\"tsuru oriental\"],\"articleSection\":[\"Curti\u00e7\u00e3o\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.pqn.com.br\/portal\/#\/schema\/person\/bd54e0682ae91879b6f7dc07b961c245\",\"name\":\"Reda\u00e7\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.pqn.com.br\/portal\/#personlogo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b39040046de680a8fa133f3a97535d1f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b39040046de680a8fa133f3a97535d1f?s=96&d=mm&r=g\",\"caption\":\"Reda\u00e7\u00e3o\"},\"url\":\"https:\/\/www.pqn.com.br\/portal\/author\/robson-abreu\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Johnny Herno apresenta o \"berimlata\"","description":"PQN - O portal da Comunica\u00e7\u00e3o!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pqn.com.br\/portal\/johnny-herno-apresenta-o-berimlata\/","og_locale":"pt_BR","og_type":"article","og_title":"Johnny Herno apresenta o \"berimlata\"","og_description":"PQN - O portal da Comunica\u00e7\u00e3o!","og_url":"https:\/\/www.pqn.com.br\/portal\/johnny-herno-apresenta-o-berimlata\/","og_site_name":"PQN - O portal da Comunica\u00e7\u00e3o!","article_published_time":"2024-04-11T20:00:03+00:00","og_image":[{"width":600,"height":270,"url":"https:\/\/www.pqn.com.br\/portal\/wp-content\/uploads\/2024\/04\/Johnny-Herno-1-Foto-Pablo-Bernardo.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Person","Organization"],"@id":"https:\/\/www.pqn.com.br\/portal\/#\/schema\/person\/641f45d95f0e5edb9d04765e83d61524","name":"Americo Alexandre Cianfarani Xavier","image":{"@type":"ImageObject","@id":"https:\/\/www.pqn.com.br\/portal\/#personlogo","inLanguage":"pt-BR","url":"https:\/\/secure.gravatar.com\/avatar\/a90e5be7c65885cf85322a30c9d98842?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a90e5be7c65885cf85322a30c9d98842?s=96&d=mm&r=g","caption":"Americo Alexandre Cianfarani Xavier"},"logo":{"@id":"https:\/\/www.pqn.com.br\/portal\/#personlogo"}},{"@type":"WebSite","@id":"https:\/\/www.pqn.com.br\/portal\/#website","url":"https:\/\/www.pqn.com.br\/portal\/","name":"PQN - O portal da Comunica\u00e7\u00e3o!","description":"","publisher":{"@id":"https:\/\/www.pqn.com.br\/portal\/#\/schema\/person\/641f45d95f0e5edb9d04765e83d61524"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pqn.com.br\/portal\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","@id":"https:\/\/www.pqn.com.br\/portal\/johnny-herno-apresenta-o-berimlata\/#primaryimage","inLanguage":"pt-BR","url":"https:\/\/www.pqn.com.br\/portal\/wp-content\/uploads\/2024\/04\/Johnny-Herno-1-Foto-Pablo-Bernardo.jpg","contentUrl":"https:\/\/www.pqn.com.br\/portal\/wp-content\/uploads\/2024\/04\/Johnny-Herno-1-Foto-Pablo-Bernardo.jpg","width":600,"height":270,"caption":"Foto: Pablo Bernardo"},{"@type":"WebPage","@id":"https:\/\/www.pqn.com.br\/portal\/johnny-herno-apresenta-o-berimlata\/#webpage","url":"https:\/\/www.pqn.com.br\/portal\/johnny-herno-apresenta-o-berimlata\/","name":"Johnny Herno apresenta o \"berimlata\"","isPartOf":{"@id":"https:\/\/www.pqn.com.br\/portal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pqn.com.br\/portal\/johnny-herno-apresenta-o-berimlata\/#primaryimage"},"datePublished":"2024-04-11T20:00:03+00:00","dateModified":"2024-04-11T20:00:03+00:00","description":"PQN - O portal da Comunica\u00e7\u00e3o!","breadcrumb":{"@id":"https:\/\/www.pqn.com.br\/portal\/johnny-herno-apresenta-o-berimlata\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pqn.com.br\/portal\/johnny-herno-apresenta-o-berimlata\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.pqn.com.br\/portal\/johnny-herno-apresenta-o-berimlata\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.pqn.com.br\/portal\/"},{"@type":"ListItem","position":2,"name":"Johnny Herno apresenta o &#8220;berimlata&#8221;"}]},{"@type":"Article","@id":"https:\/\/www.pqn.com.br\/portal\/johnny-herno-apresenta-o-berimlata\/#article","isPartOf":{"@id":"https:\/\/www.pqn.com.br\/portal\/johnny-herno-apresenta-o-berimlata\/#webpage"},"author":{"@id":"https:\/\/www.pqn.com.br\/portal\/#\/schema\/person\/bd54e0682ae91879b6f7dc07b961c245"},"headline":"Johnny Herno apresenta o &#8220;berimlata&#8221;","datePublished":"2024-04-11T20:00:03+00:00","dateModified":"2024-04-11T20:00:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.pqn.com.br\/portal\/johnny-herno-apresenta-o-berimlata\/#webpage"},"wordCount":1220,"publisher":{"@id":"https:\/\/www.pqn.com.br\/portal\/#\/schema\/person\/641f45d95f0e5edb9d04765e83d61524"},"image":{"@id":"https:\/\/www.pqn.com.br\/portal\/johnny-herno-apresenta-o-berimlata\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pqn.com.br\/portal\/wp-content\/uploads\/2024\/04\/Johnny-Herno-1-Foto-Pablo-Bernardo.jpg","keywords":["\"berimlata\"","Babilack Bah","capa","Johnny Herno","Parque Ecol\u00f3gico e Cultural Professor Marcos Mazzoni","tsuru oriental"],"articleSection":["Curti\u00e7\u00e3o"],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.pqn.com.br\/portal\/#\/schema\/person\/bd54e0682ae91879b6f7dc07b961c245","name":"Reda\u00e7\u00e3o","image":{"@type":"ImageObject","@id":"https:\/\/www.pqn.com.br\/portal\/#personlogo","inLanguage":"pt-BR","url":"https:\/\/secure.gravatar.com\/avatar\/b39040046de680a8fa133f3a97535d1f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b39040046de680a8fa133f3a97535d1f?s=96&d=mm&r=g","caption":"Reda\u00e7\u00e3o"},"url":"https:\/\/www.pqn.com.br\/portal\/author\/robson-abreu\/"}]}},"_links":{"self":[{"href":"https:\/\/www.pqn.com.br\/portal\/wp-json\/wp\/v2\/posts\/12089"}],"collection":[{"href":"https:\/\/www.pqn.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pqn.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pqn.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pqn.com.br\/portal\/wp-json\/wp\/v2\/comments?post=12089"}],"version-history":[{"count":1,"href":"https:\/\/www.pqn.com.br\/portal\/wp-json\/wp\/v2\/posts\/12089\/revisions"}],"predecessor-version":[{"id":12091,"href":"https:\/\/www.pqn.com.br\/portal\/wp-json\/wp\/v2\/posts\/12089\/revisions\/12091"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pqn.com.br\/portal\/wp-json\/wp\/v2\/media\/12090"}],"wp:attachment":[{"href":"https:\/\/www.pqn.com.br\/portal\/wp-json\/wp\/v2\/media?parent=12089"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pqn.com.br\/portal\/wp-json\/wp\/v2\/categories?post=12089"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pqn.com.br\/portal\/wp-json\/wp\/v2\/tags?post=12089"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}