<ul id="share-buttons"><li class="facebook"><div class="fb-like" data-href="https://www.pqn.com.br/portal/pet-cafe-promove-happy-hour-de-dia-dos-namorados/" data-send="false" data-layout="button_count" data-width="66" data-show-faces="false"></div></li><li class="twitter"><a href="http://twitter.com/share" class="twitter-share-button" data-url="https://www.pqn.com.br/portal/pet-cafe-promove-happy-hour-de-dia-dos-namorados/" data-count="none">Tweet</a></li><li class="google"><div class="g-plusone" data-size="medium" data-href="https://www.pqn.com.br/portal/pet-cafe-promove-happy-hour-de-dia-dos-namorados/"></div></li><li class="linkedin"><script type="IN/Share" data-url="https://www.pqn.com.br/portal/pet-cafe-promove-happy-hour-de-dia-dos-namorados/" data-counter="right"></script></li></ul>{"id":13110,"date":"2025-06-05T17:59:25","date_gmt":"2025-06-05T20:59:25","guid":{"rendered":"https:\/\/www.pqn.com.br\/portal\/?p=13110"},"modified":"2025-06-05T17:59:25","modified_gmt":"2025-06-05T20:59:25","slug":"pet-cafe-promove-happy-hour-de-dia-dos-namorados","status":"publish","type":"post","link":"https:\/\/www.pqn.com.br\/portal\/pet-cafe-promove-happy-hour-de-dia-dos-namorados\/","title":{"rendered":"Pet Caf\u00e9 promove Happy Hour de Dia dos Namorados"},"content":{"rendered":"<div id=\"attachment_13111\" style=\"width: 610px\" class=\"wp-caption alignleft\"><img aria-describedby=\"caption-attachment-13111\" loading=\"lazy\" class=\"size-full wp-image-13111\" src=\"https:\/\/www.pqn.com.br\/portal\/wp-content\/uploads\/2025\/06\/Dia-dos-Namorados-PetCafe-Divulgacao.jpg\" alt=\"\" width=\"600\" height=\"454\" srcset=\"https:\/\/www.pqn.com.br\/portal\/wp-content\/uploads\/2025\/06\/Dia-dos-Namorados-PetCafe-Divulgacao.jpg 600w, https:\/\/www.pqn.com.br\/portal\/wp-content\/uploads\/2025\/06\/Dia-dos-Namorados-PetCafe-Divulgacao-300x227.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><p id=\"caption-attachment-13111\" class=\"wp-caption-text\">Divulga\u00e7\u00e3o<\/p><\/div>\n<p>No dia 12 de junho, o Pet Caf\u00e9 promove um happy hour especial em comemora\u00e7\u00e3o ao Dia dos Namorados, dedicado a casais que compartilham o amor tamb\u00e9m com seus pets. Com ambiente acolhedor, luzes suaves e um card\u00e1pio exclusivo de namorados, a noite promete ser inesquec\u00edvel para quem n\u00e3o abre m\u00e3o de celebrar com os companheiros de quatro patas.<\/p>\n<p>O menu criado para a data aposta em combina\u00e7\u00f5es saborosas e receitas afetivas, pensadas para agradar a dois. Entre os destaque para petiscar, o P\u00e3o de queijo frito com barbecue de goiabada e o Fil\u00e9 Mignon ao molho gorgonzola com cesta de p\u00e3es. Para o jantar, op\u00e7\u00f5es como o Estrogonofe de Mignon e a Massa Alfredo. A carta de drinks contempla desde cl\u00e1ssicos at\u00e9 cria\u00e7\u00f5es autorais, como o Gin Tropical e o Brazilian Beach cocktail, enquanto sobremesas como a Torta de Ninho e o Brownie com sorvete finalizam a experi\u00eancia. Como diferencial, h\u00e1 tamb\u00e9m um card\u00e1pio especial para pets, desenvolvido com acompanhamento dos nutricionistas da marca Dog Natural Food. Entre as op\u00e7\u00f5es est\u00e3o Caoxinha, Bolinho de carne, Risoto de peixe, Mac\u00e3orronada, Cerveja pet sabor carne e Vinho pet.<\/p>\n<p>Como diferencial, os pets que acompanharem seus tutores receber\u00e3o um mimo exclusivo, tornando a noite agrad\u00e1vel para toda a fam\u00edlia. As reservas devem ser feitas antecipadamente atrav\u00e9s do WhatsApp (31) 98425-0092 e est\u00e3o sujeitas \u00e0 disponibilidade.<\/p>\n<p><strong>Sobre o PetCaf\u00e9:<\/strong><br \/>\nO PetCaf\u00e9 \u00e9 uma cafeteria pet friendly localizada na Savassi, em Belo Horizonte, que oferece um espa\u00e7o acolhedor para pessoas e seus animais de estima\u00e7\u00e3o desfrutarem juntos. Com uma variedade de op\u00e7\u00f5es de caf\u00e9 da manh\u00e3, brunch, almo\u00e7o e lanches, o PetCaf\u00e9 \u00e9 o local ideal para quem busca momentos especiais ao lado de seus amigos peludos, que podem circular livremente pelo espa\u00e7o. O caf\u00e9 conta ainda com o Cat Place, espa\u00e7o de intera\u00e7\u00e3o com gatos, que tamb\u00e9m podem ser adotados.<\/p>\n<p><strong>SERVI\u00c7O:<\/strong><br \/>\nHappy Hour de Dia dos Namorados no Pet Caf\u00e9<br \/>\n12 de junho<br \/>\nda 17h \u00e0s 23h<br \/>\nRua Sergipe, 1187, na Savassi.<br \/>\nReservas via WhatsApp &#8211; (31) 98425-0092<\/p>\n<p><strong>PetCaf\u00e9<\/strong><br \/>\nEndere\u00e7o: Rua Sergipe, 1187, na Savassi.<br \/>\nFuncionamento: Segunda a sexta-feira: das 10h \u00e0s 19h | S\u00e1bados e domingos: das 9h \u00e0s 19h<br \/>\nInstagram: @petcafebh<br \/>\n<a href=\"http:\/\/www.petcafe.com.br\">http:\/\/www.petcafe.com.br<\/a><\/p>\n<p><strong>Romano Comunica\u00e7\u00e3o<\/strong><br \/>\nWhatsapp Corporativo: 31 97101 6879<br \/>\nGabriela Pacheco &#8211; 31 991550961 \/ gabriela@romanocomunicacao.com<br \/>\nThiago Romano \u2013 31 99282 6879 \/ thiago@romanocomunicacao.com<br \/>\nInstagram: @romanocomunicacao<\/p>\n","protected":false},"excerpt":{"rendered":"<p> [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":13111,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[88],"tags":[15717,48,15716,15715,5581],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pet Caf\u00e9 promove Happy Hour de Dia dos Namorados<\/title>\n<meta name=\"description\" content=\"PQN - O portal da Comunica\u00e7\u00e3o!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pqn.com.br\/portal\/pet-cafe-promove-happy-hour-de-dia-dos-namorados\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pet Caf\u00e9 promove Happy Hour de Dia dos Namorados\" \/>\n<meta property=\"og:description\" content=\"PQN - O portal da Comunica\u00e7\u00e3o!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pqn.com.br\/portal\/pet-cafe-promove-happy-hour-de-dia-dos-namorados\/\" \/>\n<meta property=\"og:site_name\" content=\"PQN - O portal da Comunica\u00e7\u00e3o!\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-05T20:59:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pqn.com.br\/portal\/wp-content\/uploads\/2025\/06\/Dia-dos-Namorados-PetCafe-Divulgacao.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"454\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/www.pqn.com.br\/portal\/#\/schema\/person\/641f45d95f0e5edb9d04765e83d61524\",\"name\":\"Americo Alexandre Cianfarani Xavier\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.pqn.com.br\/portal\/#personlogo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a90e5be7c65885cf85322a30c9d98842?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a90e5be7c65885cf85322a30c9d98842?s=96&d=mm&r=g\",\"caption\":\"Americo Alexandre Cianfarani Xavier\"},\"logo\":{\"@id\":\"https:\/\/www.pqn.com.br\/portal\/#personlogo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pqn.com.br\/portal\/#website\",\"url\":\"https:\/\/www.pqn.com.br\/portal\/\",\"name\":\"PQN - O portal da Comunica\u00e7\u00e3o!\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.pqn.com.br\/portal\/#\/schema\/person\/641f45d95f0e5edb9d04765e83d61524\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pqn.com.br\/portal\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.pqn.com.br\/portal\/pet-cafe-promove-happy-hour-de-dia-dos-namorados\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/www.pqn.com.br\/portal\/wp-content\/uploads\/2025\/06\/Dia-dos-Namorados-PetCafe-Divulgacao.jpg\",\"contentUrl\":\"https:\/\/www.pqn.com.br\/portal\/wp-content\/uploads\/2025\/06\/Dia-dos-Namorados-PetCafe-Divulgacao.jpg\",\"width\":600,\"height\":454,\"caption\":\"Divulga\u00e7\u00e3o\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pqn.com.br\/portal\/pet-cafe-promove-happy-hour-de-dia-dos-namorados\/#webpage\",\"url\":\"https:\/\/www.pqn.com.br\/portal\/pet-cafe-promove-happy-hour-de-dia-dos-namorados\/\",\"name\":\"Pet Caf\u00e9 promove Happy Hour de Dia dos Namorados\",\"isPartOf\":{\"@id\":\"https:\/\/www.pqn.com.br\/portal\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.pqn.com.br\/portal\/pet-cafe-promove-happy-hour-de-dia-dos-namorados\/#primaryimage\"},\"datePublished\":\"2025-06-05T20:59:25+00:00\",\"dateModified\":\"2025-06-05T20:59:25+00:00\",\"description\":\"PQN - O portal da Comunica\u00e7\u00e3o!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.pqn.com.br\/portal\/pet-cafe-promove-happy-hour-de-dia-dos-namorados\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.pqn.com.br\/portal\/pet-cafe-promove-happy-hour-de-dia-dos-namorados\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.pqn.com.br\/portal\/pet-cafe-promove-happy-hour-de-dia-dos-namorados\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.pqn.com.br\/portal\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pet Caf\u00e9 promove Happy Hour de Dia dos Namorados\"}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/www.pqn.com.br\/portal\/pet-cafe-promove-happy-hour-de-dia-dos-namorados\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.pqn.com.br\/portal\/pet-cafe-promove-happy-hour-de-dia-dos-namorados\/#webpage\"},\"author\":{\"@id\":\"https:\/\/www.pqn.com.br\/portal\/#\/schema\/person\/bd54e0682ae91879b6f7dc07b961c245\"},\"headline\":\"Pet Caf\u00e9 promove Happy Hour de Dia dos Namorados\",\"datePublished\":\"2025-06-05T20:59:25+00:00\",\"dateModified\":\"2025-06-05T20:59:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.pqn.com.br\/portal\/pet-cafe-promove-happy-hour-de-dia-dos-namorados\/#webpage\"},\"wordCount\":425,\"publisher\":{\"@id\":\"https:\/\/www.pqn.com.br\/portal\/#\/schema\/person\/641f45d95f0e5edb9d04765e83d61524\"},\"image\":{\"@id\":\"https:\/\/www.pqn.com.br\/portal\/pet-cafe-promove-happy-hour-de-dia-dos-namorados\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.pqn.com.br\/portal\/wp-content\/uploads\/2025\/06\/Dia-dos-Namorados-PetCafe-Divulgacao.jpg\",\"keywords\":[\"cafeteria pet friendly\",\"capa\",\"Happy Hour de Dia dos Namorados\",\"Pet Caf\u00e9\",\"Romano Comunica\u00e7\u00e3o\"],\"articleSection\":[\"Fornadas\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.pqn.com.br\/portal\/#\/schema\/person\/bd54e0682ae91879b6f7dc07b961c245\",\"name\":\"Reda\u00e7\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.pqn.com.br\/portal\/#personlogo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b39040046de680a8fa133f3a97535d1f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b39040046de680a8fa133f3a97535d1f?s=96&d=mm&r=g\",\"caption\":\"Reda\u00e7\u00e3o\"},\"url\":\"https:\/\/www.pqn.com.br\/portal\/author\/robson-abreu\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pet Caf\u00e9 promove Happy Hour de Dia dos Namorados","description":"PQN - O portal da Comunica\u00e7\u00e3o!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pqn.com.br\/portal\/pet-cafe-promove-happy-hour-de-dia-dos-namorados\/","og_locale":"pt_BR","og_type":"article","og_title":"Pet Caf\u00e9 promove Happy Hour de Dia dos Namorados","og_description":"PQN - O portal da Comunica\u00e7\u00e3o!","og_url":"https:\/\/www.pqn.com.br\/portal\/pet-cafe-promove-happy-hour-de-dia-dos-namorados\/","og_site_name":"PQN - O portal da Comunica\u00e7\u00e3o!","article_published_time":"2025-06-05T20:59:25+00:00","og_image":[{"width":600,"height":454,"url":"https:\/\/www.pqn.com.br\/portal\/wp-content\/uploads\/2025\/06\/Dia-dos-Namorados-PetCafe-Divulgacao.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Person","Organization"],"@id":"https:\/\/www.pqn.com.br\/portal\/#\/schema\/person\/641f45d95f0e5edb9d04765e83d61524","name":"Americo Alexandre Cianfarani Xavier","image":{"@type":"ImageObject","@id":"https:\/\/www.pqn.com.br\/portal\/#personlogo","inLanguage":"pt-BR","url":"https:\/\/secure.gravatar.com\/avatar\/a90e5be7c65885cf85322a30c9d98842?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a90e5be7c65885cf85322a30c9d98842?s=96&d=mm&r=g","caption":"Americo Alexandre Cianfarani Xavier"},"logo":{"@id":"https:\/\/www.pqn.com.br\/portal\/#personlogo"}},{"@type":"WebSite","@id":"https:\/\/www.pqn.com.br\/portal\/#website","url":"https:\/\/www.pqn.com.br\/portal\/","name":"PQN - O portal da Comunica\u00e7\u00e3o!","description":"","publisher":{"@id":"https:\/\/www.pqn.com.br\/portal\/#\/schema\/person\/641f45d95f0e5edb9d04765e83d61524"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pqn.com.br\/portal\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","@id":"https:\/\/www.pqn.com.br\/portal\/pet-cafe-promove-happy-hour-de-dia-dos-namorados\/#primaryimage","inLanguage":"pt-BR","url":"https:\/\/www.pqn.com.br\/portal\/wp-content\/uploads\/2025\/06\/Dia-dos-Namorados-PetCafe-Divulgacao.jpg","contentUrl":"https:\/\/www.pqn.com.br\/portal\/wp-content\/uploads\/2025\/06\/Dia-dos-Namorados-PetCafe-Divulgacao.jpg","width":600,"height":454,"caption":"Divulga\u00e7\u00e3o"},{"@type":"WebPage","@id":"https:\/\/www.pqn.com.br\/portal\/pet-cafe-promove-happy-hour-de-dia-dos-namorados\/#webpage","url":"https:\/\/www.pqn.com.br\/portal\/pet-cafe-promove-happy-hour-de-dia-dos-namorados\/","name":"Pet Caf\u00e9 promove Happy Hour de Dia dos Namorados","isPartOf":{"@id":"https:\/\/www.pqn.com.br\/portal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pqn.com.br\/portal\/pet-cafe-promove-happy-hour-de-dia-dos-namorados\/#primaryimage"},"datePublished":"2025-06-05T20:59:25+00:00","dateModified":"2025-06-05T20:59:25+00:00","description":"PQN - O portal da Comunica\u00e7\u00e3o!","breadcrumb":{"@id":"https:\/\/www.pqn.com.br\/portal\/pet-cafe-promove-happy-hour-de-dia-dos-namorados\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pqn.com.br\/portal\/pet-cafe-promove-happy-hour-de-dia-dos-namorados\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.pqn.com.br\/portal\/pet-cafe-promove-happy-hour-de-dia-dos-namorados\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.pqn.com.br\/portal\/"},{"@type":"ListItem","position":2,"name":"Pet Caf\u00e9 promove Happy Hour de Dia dos Namorados"}]},{"@type":"Article","@id":"https:\/\/www.pqn.com.br\/portal\/pet-cafe-promove-happy-hour-de-dia-dos-namorados\/#article","isPartOf":{"@id":"https:\/\/www.pqn.com.br\/portal\/pet-cafe-promove-happy-hour-de-dia-dos-namorados\/#webpage"},"author":{"@id":"https:\/\/www.pqn.com.br\/portal\/#\/schema\/person\/bd54e0682ae91879b6f7dc07b961c245"},"headline":"Pet Caf\u00e9 promove Happy Hour de Dia dos Namorados","datePublished":"2025-06-05T20:59:25+00:00","dateModified":"2025-06-05T20:59:25+00:00","mainEntityOfPage":{"@id":"https:\/\/www.pqn.com.br\/portal\/pet-cafe-promove-happy-hour-de-dia-dos-namorados\/#webpage"},"wordCount":425,"publisher":{"@id":"https:\/\/www.pqn.com.br\/portal\/#\/schema\/person\/641f45d95f0e5edb9d04765e83d61524"},"image":{"@id":"https:\/\/www.pqn.com.br\/portal\/pet-cafe-promove-happy-hour-de-dia-dos-namorados\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pqn.com.br\/portal\/wp-content\/uploads\/2025\/06\/Dia-dos-Namorados-PetCafe-Divulgacao.jpg","keywords":["cafeteria pet friendly","capa","Happy Hour de Dia dos Namorados","Pet Caf\u00e9","Romano Comunica\u00e7\u00e3o"],"articleSection":["Fornadas"],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.pqn.com.br\/portal\/#\/schema\/person\/bd54e0682ae91879b6f7dc07b961c245","name":"Reda\u00e7\u00e3o","image":{"@type":"ImageObject","@id":"https:\/\/www.pqn.com.br\/portal\/#personlogo","inLanguage":"pt-BR","url":"https:\/\/secure.gravatar.com\/avatar\/b39040046de680a8fa133f3a97535d1f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b39040046de680a8fa133f3a97535d1f?s=96&d=mm&r=g","caption":"Reda\u00e7\u00e3o"},"url":"https:\/\/www.pqn.com.br\/portal\/author\/robson-abreu\/"}]}},"_links":{"self":[{"href":"https:\/\/www.pqn.com.br\/portal\/wp-json\/wp\/v2\/posts\/13110"}],"collection":[{"href":"https:\/\/www.pqn.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pqn.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pqn.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pqn.com.br\/portal\/wp-json\/wp\/v2\/comments?post=13110"}],"version-history":[{"count":1,"href":"https:\/\/www.pqn.com.br\/portal\/wp-json\/wp\/v2\/posts\/13110\/revisions"}],"predecessor-version":[{"id":13112,"href":"https:\/\/www.pqn.com.br\/portal\/wp-json\/wp\/v2\/posts\/13110\/revisions\/13112"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pqn.com.br\/portal\/wp-json\/wp\/v2\/media\/13111"}],"wp:attachment":[{"href":"https:\/\/www.pqn.com.br\/portal\/wp-json\/wp\/v2\/media?parent=13110"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pqn.com.br\/portal\/wp-json\/wp\/v2\/categories?post=13110"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pqn.com.br\/portal\/wp-json\/wp\/v2\/tags?post=13110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}