<ul id="share-buttons"><li class="facebook"><div class="fb-like" data-href="https://www.pqn.com.br/portal/paulinho-da-viola-faz-unica-apresentacao-com-a-turne-2025-quando-o-samba-chama/" data-send="false" data-layout="button_count" data-width="66" data-show-faces="false"></div></li><li class="twitter"><a href="http://twitter.com/share" class="twitter-share-button" data-url="https://www.pqn.com.br/portal/paulinho-da-viola-faz-unica-apresentacao-com-a-turne-2025-quando-o-samba-chama/" data-count="none">Tweet</a></li><li class="google"><div class="g-plusone" data-size="medium" data-href="https://www.pqn.com.br/portal/paulinho-da-viola-faz-unica-apresentacao-com-a-turne-2025-quando-o-samba-chama/"></div></li><li class="linkedin"><script type="IN/Share" data-url="https://www.pqn.com.br/portal/paulinho-da-viola-faz-unica-apresentacao-com-a-turne-2025-quando-o-samba-chama/" data-counter="right"></script></li></ul>{"id":13113,"date":"2025-06-05T18:04:15","date_gmt":"2025-06-05T21:04:15","guid":{"rendered":"https:\/\/www.pqn.com.br\/portal\/?p=13113"},"modified":"2025-06-05T18:04:15","modified_gmt":"2025-06-05T21:04:15","slug":"paulinho-da-viola-faz-unica-apresentacao-com-a-turne-2025-quando-o-samba-chama","status":"publish","type":"post","link":"https:\/\/www.pqn.com.br\/portal\/paulinho-da-viola-faz-unica-apresentacao-com-a-turne-2025-quando-o-samba-chama\/","title":{"rendered":"Paulinho da Viola faz \u00fanica apresenta\u00e7\u00e3o com a turn\u00ea 2025 &#8220;Quando o Samba Chama&#8221;"},"content":{"rendered":"<div id=\"attachment_13114\" style=\"width: 610px\" class=\"wp-caption alignleft\"><img aria-describedby=\"caption-attachment-13114\" loading=\"lazy\" class=\"size-full wp-image-13114\" src=\"https:\/\/www.pqn.com.br\/portal\/wp-content\/uploads\/2025\/06\/PaulinhoDaViola-LeoAversa094.jpg\" alt=\"\" width=\"600\" height=\"322\" srcset=\"https:\/\/www.pqn.com.br\/portal\/wp-content\/uploads\/2025\/06\/PaulinhoDaViola-LeoAversa094.jpg 600w, https:\/\/www.pqn.com.br\/portal\/wp-content\/uploads\/2025\/06\/PaulinhoDaViola-LeoAversa094-300x161.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><p id=\"caption-attachment-13114\" class=\"wp-caption-text\">Foto: Leo Aversa<\/p><\/div>\n<p>Um dos maiores \u00edcones do samba e da m\u00fasica popular brasileira, Paulinho da Viola, faz \u00fanica apresenta\u00e7\u00e3o no Pal\u00e1cio das Artes, com a turn\u00ea \u201cQUANDO O SAMBA CHAMA\u201d, no dia 26 de julho, s\u00e1bado, \u00e0s 21 horas.<\/p>\n<p>Neste show, Paulinho da Viola vai em busca de sambas que n\u00e3o toca nos palcos h\u00e1 algum tempo, ao lado de grandes sucessos que n\u00e3o podem faltar como: Foi um rio que passou em minha vida, Argumento, Onde a dor n\u00e3o tem raz\u00e3o e Pecado Capital entre outros.<\/p>\n<p>QUANDO O SAMBA CHAMA \u00e9 um convite para celebrar a luz que o poeta reparte tanto com o p\u00fablico que o acompanha h\u00e1 muito tempo, quanto com aqueles que a cada dia descobrem em Paulinho da Viola um novo mar de poesia e m\u00fasica.<\/p>\n<p>Os ingressos est\u00e3o \u00e0 venda nas bilheterias do Pal\u00e1cio das Artes e no site Eventim.<\/p>\n<p>Na poesia de Paulinho da Viola, o mar surge como s\u00edmbolo de grandeza, mist\u00e9rio, destino e imagina\u00e7\u00e3o. Can\u00e7\u00f5es como Mar Grande, Cidade Submersa, Timoneiro, Pra jogar no oceano e Argumento encontram na for\u00e7a da \u00e1gua um simbolismo para muitas quest\u00f5es do amor e do destino.<\/p>\n<p>Uma outra met\u00e1fora menos conhecida na poesia de Paulinho \u00e9 a da chama. N\u00e3o \u00e9 o mesmo que o fogo, que arde e representa a paix\u00e3o, o impulso e o desejo. A chama \u00e9 o que permanece vivo por um longo tempo, \u00e9 o que n\u00e3o se extingui ainda que muitos pensam que n\u00e3o est\u00e1 mais l\u00e1. A chama \u00e9 perene, ao contr\u00e1rio do fogo que queima abruptamente.<\/p>\n<p>A chama do samba permanece acesa em Paulinho da Viola perto de completar 6 d\u00e9cadas de carreira. Esta chama n\u00e3o apenas o ilumina, mas o chama no sentido de convoc\u00e1-lo para como diz o verso de uma de suas m\u00fasicas, repartir a sua luz:<\/p>\n<p>Mas se o tempo se acha no sol do poente<br \/>\nE do c\u00e9u se retira um peda\u00e7o do azul<br \/>\nO poeta ressurge e lan\u00e7a no ar a semente<br \/>\nE reparte feliz a sua luz<\/p>\n<p>Quando o Samba Chama (Paulinho da Viola)<\/p>\n<p><strong>Sobre Paulinho da Viola:<\/strong><\/p>\n<p>Nascido em um ambiente musical no tradicional bairro de Botafogo, na zona sul do Rio de Janeiro, Paulinho da Viola presenciou desde cedo os encontros musicais promovidos por seu pai, o violonista Cesar Faria. Nessas oportunidades, pode ver em sua pr\u00f3pria casa, m\u00fasicos como Pixinguinha e Jacob do Bandolim.<br \/>\nEntre os principais reconhecimentos dados a Paulinho da Viola desde o in\u00edcio de sua carreira, podemos destacar:<br \/>\n1968: Golfinho de Ouro<br \/>\n1969: 1\u00ba lugar no Festival de MPB da TV Record<br \/>\n1982 e 1997: Pr\u00eamio APCA de melhor show do ano<br \/>\n1992: Pr\u00eamio Shell<br \/>\nPr\u00eamio Sharp: 9 trof\u00e9us ao longo da carreira<br \/>\nLatin Grammy 2008: Melhor \u00e1lbum de samba\/pagode<br \/>\nLatin Grammy 2021: Melhor \u00e1lbum de samba\/pagode<\/p>\n<p>O reconhecimento da import\u00e2ncia da obra de Paulinho da Viola n\u00e3o \u00e9 restrito \u00e0s premia\u00e7\u00f5es. Entre as condecora\u00e7\u00f5es mais significativas, podemos destacar:<br \/>\n1985: Chevalier de L\u2019ordre des Art et des Letters (concedida pelo governo da Fran\u00e7a)<br \/>\n2001: Ordem do M\u00e9rito Cultural<\/p>\n<p>Outro sinal da representatividade de Paulinho da Viola foi o fato de ter sido escolhido para cantar o Hino Nacional na abertura das Olimp\u00edadas do Rio de Janeiro de 2016.<\/p>\n<p>Pelo mundo, Paulinho da Viola foi convidado a se apresentar nos principais palcos internacionais, entre eles, o concerto realizado no palco principal do Carnegie Hall em 2012 que rendeu uma grande mat\u00e9ria no jornal americano The New York Times.<\/p>\n<p>Em 2016, Paulinho da Viola foi homenageado com dois concertos realizados pela Orquestra Filarm\u00f4nica de Rotterdam na sala de concerto De Doelen, na Holanda.<\/p>\n<p>Em 2018, a escola de samba japonesa G.R.E.S BARBAROS realizou seu desfile sobre a obra de Paulinho da Viola no Asakusa Samba Carnival, uma das maiores festas de rua de T\u00f3quio, que re\u00fane anualmente 500.000 espectadores na capital japonesa.<\/p>\n<p><strong>SERVI\u00c7OS<\/strong><br \/>\nPaulinho da Viola | \u201cQuando o Samba Chama\u201d<br \/>\nDia: 26 de julho (s\u00e1bado)<br \/>\nLocal: Grande Teatro do Pal\u00e1cio das Artes (Av. Afonso Pena, 1.537 &#8211; Belo Horizonte \u2013 MG)<br \/>\nHor\u00e1rio: 21h<br \/>\nValor dos ingressos: a partir de R$ 130,00<br \/>\nPlateia I: a partir de R$ 270,00<br \/>\nPlateia II: a partir de R$ 230,00<br \/>\nSuperior: a partir de R$ 130,00<br \/>\n*** Fam\u00edlia &amp; Amigos: Venda exclusiva e promocional para pacotes a partir de 02 ingressos. V\u00e1lido somente para ingresso inteira. Desconto n\u00e3o cumulativo com meia entrada e\/ou outras promo\u00e7\u00f5es.<br \/>\nClassifica\u00e7\u00e3o Livre.<br \/>\nIngressos: Bilheteria do teatro Pal\u00e1cio das Artes e pelo site Eventim.<\/p>\n<p>Mais informa\u00e7\u00f5es: (31) 97222-2424<br \/>\nRealiza\u00e7\u00e3o: \u00cdmpar Shows<\/p>\n<p><strong>Vianello Assessoria<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p> [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":13114,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[88],"tags":[48,15720,133,15718,15719,2289],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Paulinho da Viola faz \u00fanica apresenta\u00e7\u00e3o com a turn\u00ea 2025 &quot;Quando o Samba Chama&quot;<\/title>\n<meta name=\"description\" content=\"PQN - O portal da Comunica\u00e7\u00e3o!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pqn.com.br\/portal\/paulinho-da-viola-faz-unica-apresentacao-com-a-turne-2025-quando-o-samba-chama\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Paulinho da Viola faz \u00fanica apresenta\u00e7\u00e3o com a turn\u00ea 2025 &quot;Quando o Samba Chama&quot;\" \/>\n<meta property=\"og:description\" content=\"PQN - O portal da Comunica\u00e7\u00e3o!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pqn.com.br\/portal\/paulinho-da-viola-faz-unica-apresentacao-com-a-turne-2025-quando-o-samba-chama\/\" \/>\n<meta property=\"og:site_name\" content=\"PQN - O portal da Comunica\u00e7\u00e3o!\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-05T21:04:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pqn.com.br\/portal\/wp-content\/uploads\/2025\/06\/PaulinhoDaViola-LeoAversa094.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"322\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/www.pqn.com.br\/portal\/#\/schema\/person\/641f45d95f0e5edb9d04765e83d61524\",\"name\":\"Americo Alexandre Cianfarani Xavier\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.pqn.com.br\/portal\/#personlogo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a90e5be7c65885cf85322a30c9d98842?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a90e5be7c65885cf85322a30c9d98842?s=96&d=mm&r=g\",\"caption\":\"Americo Alexandre Cianfarani Xavier\"},\"logo\":{\"@id\":\"https:\/\/www.pqn.com.br\/portal\/#personlogo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pqn.com.br\/portal\/#website\",\"url\":\"https:\/\/www.pqn.com.br\/portal\/\",\"name\":\"PQN - O portal da Comunica\u00e7\u00e3o!\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.pqn.com.br\/portal\/#\/schema\/person\/641f45d95f0e5edb9d04765e83d61524\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pqn.com.br\/portal\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.pqn.com.br\/portal\/paulinho-da-viola-faz-unica-apresentacao-com-a-turne-2025-quando-o-samba-chama\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/www.pqn.com.br\/portal\/wp-content\/uploads\/2025\/06\/PaulinhoDaViola-LeoAversa094.jpg\",\"contentUrl\":\"https:\/\/www.pqn.com.br\/portal\/wp-content\/uploads\/2025\/06\/PaulinhoDaViola-LeoAversa094.jpg\",\"width\":600,\"height\":322,\"caption\":\"Foto: Leo Aversa\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pqn.com.br\/portal\/paulinho-da-viola-faz-unica-apresentacao-com-a-turne-2025-quando-o-samba-chama\/#webpage\",\"url\":\"https:\/\/www.pqn.com.br\/portal\/paulinho-da-viola-faz-unica-apresentacao-com-a-turne-2025-quando-o-samba-chama\/\",\"name\":\"Paulinho da Viola faz \u00fanica apresenta\u00e7\u00e3o com a turn\u00ea 2025 \\\"Quando o Samba Chama\\\"\",\"isPartOf\":{\"@id\":\"https:\/\/www.pqn.com.br\/portal\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.pqn.com.br\/portal\/paulinho-da-viola-faz-unica-apresentacao-com-a-turne-2025-quando-o-samba-chama\/#primaryimage\"},\"datePublished\":\"2025-06-05T21:04:15+00:00\",\"dateModified\":\"2025-06-05T21:04:15+00:00\",\"description\":\"PQN - O portal da Comunica\u00e7\u00e3o!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.pqn.com.br\/portal\/paulinho-da-viola-faz-unica-apresentacao-com-a-turne-2025-quando-o-samba-chama\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.pqn.com.br\/portal\/paulinho-da-viola-faz-unica-apresentacao-com-a-turne-2025-quando-o-samba-chama\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.pqn.com.br\/portal\/paulinho-da-viola-faz-unica-apresentacao-com-a-turne-2025-quando-o-samba-chama\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.pqn.com.br\/portal\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Paulinho da Viola faz \u00fanica apresenta\u00e7\u00e3o com a turn\u00ea 2025 &#8220;Quando o Samba Chama&#8221;\"}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/www.pqn.com.br\/portal\/paulinho-da-viola-faz-unica-apresentacao-com-a-turne-2025-quando-o-samba-chama\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.pqn.com.br\/portal\/paulinho-da-viola-faz-unica-apresentacao-com-a-turne-2025-quando-o-samba-chama\/#webpage\"},\"author\":{\"@id\":\"https:\/\/www.pqn.com.br\/portal\/#\/schema\/person\/bd54e0682ae91879b6f7dc07b961c245\"},\"headline\":\"Paulinho da Viola faz \u00fanica apresenta\u00e7\u00e3o com a turn\u00ea 2025 &#8220;Quando o Samba Chama&#8221;\",\"datePublished\":\"2025-06-05T21:04:15+00:00\",\"dateModified\":\"2025-06-05T21:04:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.pqn.com.br\/portal\/paulinho-da-viola-faz-unica-apresentacao-com-a-turne-2025-quando-o-samba-chama\/#webpage\"},\"wordCount\":799,\"publisher\":{\"@id\":\"https:\/\/www.pqn.com.br\/portal\/#\/schema\/person\/641f45d95f0e5edb9d04765e83d61524\"},\"image\":{\"@id\":\"https:\/\/www.pqn.com.br\/portal\/paulinho-da-viola-faz-unica-apresentacao-com-a-turne-2025-quando-o-samba-chama\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.pqn.com.br\/portal\/wp-content\/uploads\/2025\/06\/PaulinhoDaViola-LeoAversa094.jpg\",\"keywords\":[\"capa\",\"\u00cdmpar Shows\",\"Pal\u00e1cio das Artes\",\"Paulinho da Viola\",\"turn\u00ea 2025 \\\"Quando o Samba Chama\\\"\",\"Vianello Assessoria\"],\"articleSection\":[\"Fornadas\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.pqn.com.br\/portal\/#\/schema\/person\/bd54e0682ae91879b6f7dc07b961c245\",\"name\":\"Reda\u00e7\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.pqn.com.br\/portal\/#personlogo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b39040046de680a8fa133f3a97535d1f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b39040046de680a8fa133f3a97535d1f?s=96&d=mm&r=g\",\"caption\":\"Reda\u00e7\u00e3o\"},\"url\":\"https:\/\/www.pqn.com.br\/portal\/author\/robson-abreu\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Paulinho da Viola faz \u00fanica apresenta\u00e7\u00e3o com a turn\u00ea 2025 \"Quando o Samba Chama\"","description":"PQN - O portal da Comunica\u00e7\u00e3o!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pqn.com.br\/portal\/paulinho-da-viola-faz-unica-apresentacao-com-a-turne-2025-quando-o-samba-chama\/","og_locale":"pt_BR","og_type":"article","og_title":"Paulinho da Viola faz \u00fanica apresenta\u00e7\u00e3o com a turn\u00ea 2025 \"Quando o Samba Chama\"","og_description":"PQN - O portal da Comunica\u00e7\u00e3o!","og_url":"https:\/\/www.pqn.com.br\/portal\/paulinho-da-viola-faz-unica-apresentacao-com-a-turne-2025-quando-o-samba-chama\/","og_site_name":"PQN - O portal da Comunica\u00e7\u00e3o!","article_published_time":"2025-06-05T21:04:15+00:00","og_image":[{"width":600,"height":322,"url":"https:\/\/www.pqn.com.br\/portal\/wp-content\/uploads\/2025\/06\/PaulinhoDaViola-LeoAversa094.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Person","Organization"],"@id":"https:\/\/www.pqn.com.br\/portal\/#\/schema\/person\/641f45d95f0e5edb9d04765e83d61524","name":"Americo Alexandre Cianfarani Xavier","image":{"@type":"ImageObject","@id":"https:\/\/www.pqn.com.br\/portal\/#personlogo","inLanguage":"pt-BR","url":"https:\/\/secure.gravatar.com\/avatar\/a90e5be7c65885cf85322a30c9d98842?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a90e5be7c65885cf85322a30c9d98842?s=96&d=mm&r=g","caption":"Americo Alexandre Cianfarani Xavier"},"logo":{"@id":"https:\/\/www.pqn.com.br\/portal\/#personlogo"}},{"@type":"WebSite","@id":"https:\/\/www.pqn.com.br\/portal\/#website","url":"https:\/\/www.pqn.com.br\/portal\/","name":"PQN - O portal da Comunica\u00e7\u00e3o!","description":"","publisher":{"@id":"https:\/\/www.pqn.com.br\/portal\/#\/schema\/person\/641f45d95f0e5edb9d04765e83d61524"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pqn.com.br\/portal\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","@id":"https:\/\/www.pqn.com.br\/portal\/paulinho-da-viola-faz-unica-apresentacao-com-a-turne-2025-quando-o-samba-chama\/#primaryimage","inLanguage":"pt-BR","url":"https:\/\/www.pqn.com.br\/portal\/wp-content\/uploads\/2025\/06\/PaulinhoDaViola-LeoAversa094.jpg","contentUrl":"https:\/\/www.pqn.com.br\/portal\/wp-content\/uploads\/2025\/06\/PaulinhoDaViola-LeoAversa094.jpg","width":600,"height":322,"caption":"Foto: Leo Aversa"},{"@type":"WebPage","@id":"https:\/\/www.pqn.com.br\/portal\/paulinho-da-viola-faz-unica-apresentacao-com-a-turne-2025-quando-o-samba-chama\/#webpage","url":"https:\/\/www.pqn.com.br\/portal\/paulinho-da-viola-faz-unica-apresentacao-com-a-turne-2025-quando-o-samba-chama\/","name":"Paulinho da Viola faz \u00fanica apresenta\u00e7\u00e3o com a turn\u00ea 2025 \"Quando o Samba Chama\"","isPartOf":{"@id":"https:\/\/www.pqn.com.br\/portal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pqn.com.br\/portal\/paulinho-da-viola-faz-unica-apresentacao-com-a-turne-2025-quando-o-samba-chama\/#primaryimage"},"datePublished":"2025-06-05T21:04:15+00:00","dateModified":"2025-06-05T21:04:15+00:00","description":"PQN - O portal da Comunica\u00e7\u00e3o!","breadcrumb":{"@id":"https:\/\/www.pqn.com.br\/portal\/paulinho-da-viola-faz-unica-apresentacao-com-a-turne-2025-quando-o-samba-chama\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pqn.com.br\/portal\/paulinho-da-viola-faz-unica-apresentacao-com-a-turne-2025-quando-o-samba-chama\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.pqn.com.br\/portal\/paulinho-da-viola-faz-unica-apresentacao-com-a-turne-2025-quando-o-samba-chama\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.pqn.com.br\/portal\/"},{"@type":"ListItem","position":2,"name":"Paulinho da Viola faz \u00fanica apresenta\u00e7\u00e3o com a turn\u00ea 2025 &#8220;Quando o Samba Chama&#8221;"}]},{"@type":"Article","@id":"https:\/\/www.pqn.com.br\/portal\/paulinho-da-viola-faz-unica-apresentacao-com-a-turne-2025-quando-o-samba-chama\/#article","isPartOf":{"@id":"https:\/\/www.pqn.com.br\/portal\/paulinho-da-viola-faz-unica-apresentacao-com-a-turne-2025-quando-o-samba-chama\/#webpage"},"author":{"@id":"https:\/\/www.pqn.com.br\/portal\/#\/schema\/person\/bd54e0682ae91879b6f7dc07b961c245"},"headline":"Paulinho da Viola faz \u00fanica apresenta\u00e7\u00e3o com a turn\u00ea 2025 &#8220;Quando o Samba Chama&#8221;","datePublished":"2025-06-05T21:04:15+00:00","dateModified":"2025-06-05T21:04:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.pqn.com.br\/portal\/paulinho-da-viola-faz-unica-apresentacao-com-a-turne-2025-quando-o-samba-chama\/#webpage"},"wordCount":799,"publisher":{"@id":"https:\/\/www.pqn.com.br\/portal\/#\/schema\/person\/641f45d95f0e5edb9d04765e83d61524"},"image":{"@id":"https:\/\/www.pqn.com.br\/portal\/paulinho-da-viola-faz-unica-apresentacao-com-a-turne-2025-quando-o-samba-chama\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pqn.com.br\/portal\/wp-content\/uploads\/2025\/06\/PaulinhoDaViola-LeoAversa094.jpg","keywords":["capa","\u00cdmpar Shows","Pal\u00e1cio das Artes","Paulinho da Viola","turn\u00ea 2025 \"Quando o Samba Chama\"","Vianello Assessoria"],"articleSection":["Fornadas"],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.pqn.com.br\/portal\/#\/schema\/person\/bd54e0682ae91879b6f7dc07b961c245","name":"Reda\u00e7\u00e3o","image":{"@type":"ImageObject","@id":"https:\/\/www.pqn.com.br\/portal\/#personlogo","inLanguage":"pt-BR","url":"https:\/\/secure.gravatar.com\/avatar\/b39040046de680a8fa133f3a97535d1f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b39040046de680a8fa133f3a97535d1f?s=96&d=mm&r=g","caption":"Reda\u00e7\u00e3o"},"url":"https:\/\/www.pqn.com.br\/portal\/author\/robson-abreu\/"}]}},"_links":{"self":[{"href":"https:\/\/www.pqn.com.br\/portal\/wp-json\/wp\/v2\/posts\/13113"}],"collection":[{"href":"https:\/\/www.pqn.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pqn.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pqn.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pqn.com.br\/portal\/wp-json\/wp\/v2\/comments?post=13113"}],"version-history":[{"count":2,"href":"https:\/\/www.pqn.com.br\/portal\/wp-json\/wp\/v2\/posts\/13113\/revisions"}],"predecessor-version":[{"id":13116,"href":"https:\/\/www.pqn.com.br\/portal\/wp-json\/wp\/v2\/posts\/13113\/revisions\/13116"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pqn.com.br\/portal\/wp-json\/wp\/v2\/media\/13114"}],"wp:attachment":[{"href":"https:\/\/www.pqn.com.br\/portal\/wp-json\/wp\/v2\/media?parent=13113"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pqn.com.br\/portal\/wp-json\/wp\/v2\/categories?post=13113"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pqn.com.br\/portal\/wp-json\/wp\/v2\/tags?post=13113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}