<ul id="share-buttons"><li class="facebook"><div class="fb-like" data-href="https://www.pqn.com.br/portal/a-emocao-esta-presente-no-novo-clipe-de-juliano-cezar/" data-send="false" data-layout="button_count" data-width="66" data-show-faces="false"></div></li><li class="twitter"><a href="http://twitter.com/share" class="twitter-share-button" data-url="https://www.pqn.com.br/portal/a-emocao-esta-presente-no-novo-clipe-de-juliano-cezar/" data-count="none">Tweet</a></li><li class="google"><div class="g-plusone" data-size="medium" data-href="https://www.pqn.com.br/portal/a-emocao-esta-presente-no-novo-clipe-de-juliano-cezar/"></div></li><li class="linkedin"><script type="IN/Share" data-url="https://www.pqn.com.br/portal/a-emocao-esta-presente-no-novo-clipe-de-juliano-cezar/" data-counter="right"></script></li></ul>{"id":5144,"date":"2020-12-07T21:43:55","date_gmt":"2020-12-07T23:43:55","guid":{"rendered":"https:\/\/www.pqn.com.br\/portal\/?p=5144"},"modified":"2020-12-07T21:43:55","modified_gmt":"2020-12-07T23:43:55","slug":"a-emocao-esta-presente-no-novo-clipe-de-juliano-cezar","status":"publish","type":"post","link":"https:\/\/www.pqn.com.br\/portal\/a-emocao-esta-presente-no-novo-clipe-de-juliano-cezar\/","title":{"rendered":"A emo\u00e7\u00e3o est\u00e1 presente no novo clipe de Juliano Cezar"},"content":{"rendered":"<div id=\"attachment_5145\" style=\"width: 310px\" class=\"wp-caption alignleft\"><img aria-describedby=\"caption-attachment-5145\" loading=\"lazy\" class=\"size-medium wp-image-5145\" src=\"https:\/\/www.pqn.com.br\/portal\/wp-content\/uploads\/2020\/12\/Juliano-Cezar--300x150.jpg\" alt=\"\" width=\"300\" height=\"150\" srcset=\"https:\/\/www.pqn.com.br\/portal\/wp-content\/uploads\/2020\/12\/Juliano-Cezar--300x150.jpg 300w, https:\/\/www.pqn.com.br\/portal\/wp-content\/uploads\/2020\/12\/Juliano-Cezar-.jpg 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><p id=\"caption-attachment-5145\" class=\"wp-caption-text\">Foto: Flaney<\/p><\/div>\n<p>Existem cantores que se tornam a personifica\u00e7\u00e3o do g\u00eanero musical do qual eles escolheram para cantar. E Juliano Cezar \u00e9 um deles. O Cowboy Vagabundo \u00e9 sin\u00f4nimo direto de m\u00fasica sertaneja e sua m\u00fasica estar\u00e1 eternamente em nossos cora\u00e7\u00f5es e ser\u00e1 sempre trilha sonora de bons e importantes momentos de nossas vidas.<\/p>\n<p>Ao partir, o artista deixou um DVD in\u00e9dito pronto para ser lan\u00e7ado. E pin\u00e7ado desta obra, saiu uma bonita homenagem para marcar a triste data de um ano da morte do sertanejo. Ser\u00e1 lan\u00e7ado, nesta sexta-feira, dia 4, o clipe da m\u00fasica Travadinho. A faixa tamb\u00e9m estar\u00e1 dispon\u00edvel em todos os aplicativos de m\u00fasica.<\/p>\n<p>Composta por Leonardo de Sousa, Allef Rodrigues, Jo\u00e3o Roas, Wanderley Batista, Abel de Assis, Thawan Alves, Antonio Avelar, Guilherme Amaral e Guilherme de Andrade, Travadinho faz parte do \u00faltimo DVD do Juliano Cezar \u2013 Cowboy Vagabundo Pelo Brasil. O v\u00eddeo conta com a participa\u00e7\u00e3o de Reinaldo Meirelles e quem assina a produ\u00e7\u00e3o musical \u00e9 Ivan Miyazato. O instrumental \u00e9 leve e a melodia bem gostosa de ser ouvida. Baladinha especial pra dan\u00e7ar. A letra conta a hist\u00f3ria de um camarada que est\u00e1 no bar, tomando umas e outras, sofrendo pelo amor n\u00e3o correspondido. \u201cVoc\u00ea que me deixou desse jeito, travadinho travadinho. Fui descendo pinga no meu peito\u201d, canta o marcante e emocionante refr\u00e3o.<\/p>\n<p>N\u00e3o tem como n\u00e3o se emocionar ao assistir o clipe de Travadinho. A figura de Juliano Cezar no meio do palco, cantando os versos fazem com que os f\u00e3s tenham uma viagem de volta para o passado, antes do fat\u00eddico dia 31 de dezembro de 2019 e rememorem todos os lindos momentos do Cowboy fazendo seus shows pelo Brasil. Com certeza um lan\u00e7amento de extrema emo\u00e7\u00e3o. O cantor era a prata da casa do escrit\u00f3rio art\u00edstico Explosion Music e durante muito tempo foi o artista mais importante do cast.<\/p>\n<p>Apaixonado por m\u00fasica country, o cantor foi um dos primeiros a adaptar o estilo \u00e0 m\u00fasica do campo brasileira, criando o country sertanejo. E foi s\u00f3 em 1990 que Juliano Cezar conseguiu lan\u00e7ar o primeiro disco oficial da carreira. O investimento resultou em sucessos como \u201cN\u00e3o Aprendi Dizer Adeus\u201d, can\u00e7\u00e3o que anos mais tarde foi regravada pela dupla Leandro e Leonardo.<\/p>\n<p>O sucesso rendeu a ele o pr\u00eamio Sharp de melhor cantor revela\u00e7\u00e3o em 1990, al\u00e9m de shows em todas as regi\u00f5es do pa\u00eds. E a partir da\u00ed vieram outros hits rom\u00e2nticos como \u201cRumo \u00e0 Goi\u00e2nia\u201d (de 1991), \u201cBem aos Olhos da Lua\u201d (de 1997), &#8220;Faz Ela Feliz&#8221; (1998) e \u201cMalvada\u201d (2002), distribu\u00eddos em 13 discos de carreira. \u201cCowboy Vagabundo\u201d, d\u00e1 nome ao disco lan\u00e7ado em 2000, que levou o cantor \u00e0 indica\u00e7\u00e3o ao pr\u00eamio de melhor \u00e1lbum rom\u00e2ntico pelo Grammy Latino, uma das mais importantes premia\u00e7\u00f5es musicais do mundo.<\/p>\n<p>Travadinho nas Redes Sociais<br \/>\nLink PRE-SAVE: https:\/\/ps.onerpm.com\/travadinho<br \/>\nLink YOUTUBE: https:\/\/youtu.be\/Pi9ZlrASSLM<br \/>\nFacebook: https:\/\/www.facebook.com\/CantorJulianoCezar\/<br \/>\nInstagram: https:\/\/www.instagram.com\/julianocezaroficial\/<br \/>\nYoutube: http:\/\/www.youtube.com\/c\/JulianoCezarCantor<\/p>\n","protected":false},"excerpt":{"rendered":"<p> [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":5145,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[155],"tags":[6021,6018,6023,48,6015,6024,6025,6019,6014,6017,6022,6016,6020],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>A emo\u00e7\u00e3o est\u00e1 presente no novo clipe de Juliano Cezar<\/title>\n<meta name=\"description\" content=\"PQN - O portal da Comunica\u00e7\u00e3o!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pqn.com.br\/portal\/a-emocao-esta-presente-no-novo-clipe-de-juliano-cezar\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A emo\u00e7\u00e3o est\u00e1 presente no novo clipe de Juliano Cezar\" \/>\n<meta property=\"og:description\" content=\"PQN - O portal da Comunica\u00e7\u00e3o!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pqn.com.br\/portal\/a-emocao-esta-presente-no-novo-clipe-de-juliano-cezar\/\" \/>\n<meta property=\"og:site_name\" content=\"PQN - O portal da Comunica\u00e7\u00e3o!\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-07T23:43:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pqn.com.br\/portal\/wp-content\/uploads\/2020\/12\/Juliano-Cezar-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/www.pqn.com.br\/portal\/#\/schema\/person\/641f45d95f0e5edb9d04765e83d61524\",\"name\":\"Americo Alexandre Cianfarani Xavier\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.pqn.com.br\/portal\/#personlogo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a90e5be7c65885cf85322a30c9d98842?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a90e5be7c65885cf85322a30c9d98842?s=96&d=mm&r=g\",\"caption\":\"Americo Alexandre Cianfarani Xavier\"},\"logo\":{\"@id\":\"https:\/\/www.pqn.com.br\/portal\/#personlogo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pqn.com.br\/portal\/#website\",\"url\":\"https:\/\/www.pqn.com.br\/portal\/\",\"name\":\"PQN - O portal da Comunica\u00e7\u00e3o!\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.pqn.com.br\/portal\/#\/schema\/person\/641f45d95f0e5edb9d04765e83d61524\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pqn.com.br\/portal\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.pqn.com.br\/portal\/a-emocao-esta-presente-no-novo-clipe-de-juliano-cezar\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/www.pqn.com.br\/portal\/wp-content\/uploads\/2020\/12\/Juliano-Cezar-.jpg\",\"contentUrl\":\"https:\/\/www.pqn.com.br\/portal\/wp-content\/uploads\/2020\/12\/Juliano-Cezar-.jpg\",\"width\":600,\"height\":300,\"caption\":\"Foto: Flaney\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pqn.com.br\/portal\/a-emocao-esta-presente-no-novo-clipe-de-juliano-cezar\/#webpage\",\"url\":\"https:\/\/www.pqn.com.br\/portal\/a-emocao-esta-presente-no-novo-clipe-de-juliano-cezar\/\",\"name\":\"A emo\u00e7\u00e3o est\u00e1 presente no novo clipe de Juliano Cezar\",\"isPartOf\":{\"@id\":\"https:\/\/www.pqn.com.br\/portal\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.pqn.com.br\/portal\/a-emocao-esta-presente-no-novo-clipe-de-juliano-cezar\/#primaryimage\"},\"datePublished\":\"2020-12-07T23:43:55+00:00\",\"dateModified\":\"2020-12-07T23:43:55+00:00\",\"description\":\"PQN - O portal da Comunica\u00e7\u00e3o!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.pqn.com.br\/portal\/a-emocao-esta-presente-no-novo-clipe-de-juliano-cezar\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.pqn.com.br\/portal\/a-emocao-esta-presente-no-novo-clipe-de-juliano-cezar\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.pqn.com.br\/portal\/a-emocao-esta-presente-no-novo-clipe-de-juliano-cezar\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.pqn.com.br\/portal\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A emo\u00e7\u00e3o est\u00e1 presente no novo clipe de Juliano Cezar\"}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/www.pqn.com.br\/portal\/a-emocao-esta-presente-no-novo-clipe-de-juliano-cezar\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.pqn.com.br\/portal\/a-emocao-esta-presente-no-novo-clipe-de-juliano-cezar\/#webpage\"},\"author\":{\"@id\":\"https:\/\/www.pqn.com.br\/portal\/#\/schema\/person\/bd54e0682ae91879b6f7dc07b961c245\"},\"headline\":\"A emo\u00e7\u00e3o est\u00e1 presente no novo clipe de Juliano Cezar\",\"datePublished\":\"2020-12-07T23:43:55+00:00\",\"dateModified\":\"2020-12-07T23:43:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.pqn.com.br\/portal\/a-emocao-esta-presente-no-novo-clipe-de-juliano-cezar\/#webpage\"},\"wordCount\":544,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.pqn.com.br\/portal\/#\/schema\/person\/641f45d95f0e5edb9d04765e83d61524\"},\"image\":{\"@id\":\"https:\/\/www.pqn.com.br\/portal\/a-emocao-esta-presente-no-novo-clipe-de-juliano-cezar\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.pqn.com.br\/portal\/wp-content\/uploads\/2020\/12\/Juliano-Cezar-.jpg\",\"keywords\":[\"Abel de Assis\",\"Allef Rodrigues\",\"Antonio Avelar\",\"capa\",\"Cowboy Vagabundo\",\"Guilherme Amaral\",\"Guilherme de Andrade\",\"Jo\u00e3o Roas\",\"Juliano Cezar\",\"Leonardo de Sousa\",\"Thawan Alves\",\"Travadinho\",\"Wanderley Batista\"],\"articleSection\":[\"Curti\u00e7\u00e3o\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.pqn.com.br\/portal\/a-emocao-esta-presente-no-novo-clipe-de-juliano-cezar\/#respond\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.pqn.com.br\/portal\/#\/schema\/person\/bd54e0682ae91879b6f7dc07b961c245\",\"name\":\"Reda\u00e7\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.pqn.com.br\/portal\/#personlogo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b39040046de680a8fa133f3a97535d1f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b39040046de680a8fa133f3a97535d1f?s=96&d=mm&r=g\",\"caption\":\"Reda\u00e7\u00e3o\"},\"url\":\"https:\/\/www.pqn.com.br\/portal\/author\/robson-abreu\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A emo\u00e7\u00e3o est\u00e1 presente no novo clipe de Juliano Cezar","description":"PQN - O portal da Comunica\u00e7\u00e3o!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pqn.com.br\/portal\/a-emocao-esta-presente-no-novo-clipe-de-juliano-cezar\/","og_locale":"pt_BR","og_type":"article","og_title":"A emo\u00e7\u00e3o est\u00e1 presente no novo clipe de Juliano Cezar","og_description":"PQN - O portal da Comunica\u00e7\u00e3o!","og_url":"https:\/\/www.pqn.com.br\/portal\/a-emocao-esta-presente-no-novo-clipe-de-juliano-cezar\/","og_site_name":"PQN - O portal da Comunica\u00e7\u00e3o!","article_published_time":"2020-12-07T23:43:55+00:00","og_image":[{"width":600,"height":300,"url":"https:\/\/www.pqn.com.br\/portal\/wp-content\/uploads\/2020\/12\/Juliano-Cezar-.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Person","Organization"],"@id":"https:\/\/www.pqn.com.br\/portal\/#\/schema\/person\/641f45d95f0e5edb9d04765e83d61524","name":"Americo Alexandre Cianfarani Xavier","image":{"@type":"ImageObject","@id":"https:\/\/www.pqn.com.br\/portal\/#personlogo","inLanguage":"pt-BR","url":"https:\/\/secure.gravatar.com\/avatar\/a90e5be7c65885cf85322a30c9d98842?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a90e5be7c65885cf85322a30c9d98842?s=96&d=mm&r=g","caption":"Americo Alexandre Cianfarani Xavier"},"logo":{"@id":"https:\/\/www.pqn.com.br\/portal\/#personlogo"}},{"@type":"WebSite","@id":"https:\/\/www.pqn.com.br\/portal\/#website","url":"https:\/\/www.pqn.com.br\/portal\/","name":"PQN - O portal da Comunica\u00e7\u00e3o!","description":"","publisher":{"@id":"https:\/\/www.pqn.com.br\/portal\/#\/schema\/person\/641f45d95f0e5edb9d04765e83d61524"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pqn.com.br\/portal\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","@id":"https:\/\/www.pqn.com.br\/portal\/a-emocao-esta-presente-no-novo-clipe-de-juliano-cezar\/#primaryimage","inLanguage":"pt-BR","url":"https:\/\/www.pqn.com.br\/portal\/wp-content\/uploads\/2020\/12\/Juliano-Cezar-.jpg","contentUrl":"https:\/\/www.pqn.com.br\/portal\/wp-content\/uploads\/2020\/12\/Juliano-Cezar-.jpg","width":600,"height":300,"caption":"Foto: Flaney"},{"@type":"WebPage","@id":"https:\/\/www.pqn.com.br\/portal\/a-emocao-esta-presente-no-novo-clipe-de-juliano-cezar\/#webpage","url":"https:\/\/www.pqn.com.br\/portal\/a-emocao-esta-presente-no-novo-clipe-de-juliano-cezar\/","name":"A emo\u00e7\u00e3o est\u00e1 presente no novo clipe de Juliano Cezar","isPartOf":{"@id":"https:\/\/www.pqn.com.br\/portal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pqn.com.br\/portal\/a-emocao-esta-presente-no-novo-clipe-de-juliano-cezar\/#primaryimage"},"datePublished":"2020-12-07T23:43:55+00:00","dateModified":"2020-12-07T23:43:55+00:00","description":"PQN - O portal da Comunica\u00e7\u00e3o!","breadcrumb":{"@id":"https:\/\/www.pqn.com.br\/portal\/a-emocao-esta-presente-no-novo-clipe-de-juliano-cezar\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pqn.com.br\/portal\/a-emocao-esta-presente-no-novo-clipe-de-juliano-cezar\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.pqn.com.br\/portal\/a-emocao-esta-presente-no-novo-clipe-de-juliano-cezar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.pqn.com.br\/portal\/"},{"@type":"ListItem","position":2,"name":"A emo\u00e7\u00e3o est\u00e1 presente no novo clipe de Juliano Cezar"}]},{"@type":"Article","@id":"https:\/\/www.pqn.com.br\/portal\/a-emocao-esta-presente-no-novo-clipe-de-juliano-cezar\/#article","isPartOf":{"@id":"https:\/\/www.pqn.com.br\/portal\/a-emocao-esta-presente-no-novo-clipe-de-juliano-cezar\/#webpage"},"author":{"@id":"https:\/\/www.pqn.com.br\/portal\/#\/schema\/person\/bd54e0682ae91879b6f7dc07b961c245"},"headline":"A emo\u00e7\u00e3o est\u00e1 presente no novo clipe de Juliano Cezar","datePublished":"2020-12-07T23:43:55+00:00","dateModified":"2020-12-07T23:43:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.pqn.com.br\/portal\/a-emocao-esta-presente-no-novo-clipe-de-juliano-cezar\/#webpage"},"wordCount":544,"commentCount":0,"publisher":{"@id":"https:\/\/www.pqn.com.br\/portal\/#\/schema\/person\/641f45d95f0e5edb9d04765e83d61524"},"image":{"@id":"https:\/\/www.pqn.com.br\/portal\/a-emocao-esta-presente-no-novo-clipe-de-juliano-cezar\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pqn.com.br\/portal\/wp-content\/uploads\/2020\/12\/Juliano-Cezar-.jpg","keywords":["Abel de Assis","Allef Rodrigues","Antonio Avelar","capa","Cowboy Vagabundo","Guilherme Amaral","Guilherme de Andrade","Jo\u00e3o Roas","Juliano Cezar","Leonardo de Sousa","Thawan Alves","Travadinho","Wanderley Batista"],"articleSection":["Curti\u00e7\u00e3o"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.pqn.com.br\/portal\/a-emocao-esta-presente-no-novo-clipe-de-juliano-cezar\/#respond"]}]},{"@type":"Person","@id":"https:\/\/www.pqn.com.br\/portal\/#\/schema\/person\/bd54e0682ae91879b6f7dc07b961c245","name":"Reda\u00e7\u00e3o","image":{"@type":"ImageObject","@id":"https:\/\/www.pqn.com.br\/portal\/#personlogo","inLanguage":"pt-BR","url":"https:\/\/secure.gravatar.com\/avatar\/b39040046de680a8fa133f3a97535d1f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b39040046de680a8fa133f3a97535d1f?s=96&d=mm&r=g","caption":"Reda\u00e7\u00e3o"},"url":"https:\/\/www.pqn.com.br\/portal\/author\/robson-abreu\/"}]}},"_links":{"self":[{"href":"https:\/\/www.pqn.com.br\/portal\/wp-json\/wp\/v2\/posts\/5144"}],"collection":[{"href":"https:\/\/www.pqn.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pqn.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pqn.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pqn.com.br\/portal\/wp-json\/wp\/v2\/comments?post=5144"}],"version-history":[{"count":2,"href":"https:\/\/www.pqn.com.br\/portal\/wp-json\/wp\/v2\/posts\/5144\/revisions"}],"predecessor-version":[{"id":5147,"href":"https:\/\/www.pqn.com.br\/portal\/wp-json\/wp\/v2\/posts\/5144\/revisions\/5147"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pqn.com.br\/portal\/wp-json\/wp\/v2\/media\/5145"}],"wp:attachment":[{"href":"https:\/\/www.pqn.com.br\/portal\/wp-json\/wp\/v2\/media?parent=5144"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pqn.com.br\/portal\/wp-json\/wp\/v2\/categories?post=5144"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pqn.com.br\/portal\/wp-json\/wp\/v2\/tags?post=5144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}